{"id":6994,"date":"2022-01-31T11:22:21","date_gmt":"2022-01-31T10:22:21","guid":{"rendered":"https:\/\/aaferimmobilier.com\/agent\/sales-agent-dahlia\/"},"modified":"2026-06-15T16:07:45","modified_gmt":"2026-06-15T15:07:45","slug":"sales-agent-dahlia","status":"publish","type":"houzez_agent","link":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/","title":{"rendered":"Sales Agent Dahlia"},"content":{"rendered":"","protected":false},"featured_media":2743,"parent":0,"menu_order":0,"template":"","agent_category":[],"agent_city":[],"class_list":["post-6994","houzez_agent","type-houzez_agent","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"agent_meta":{"_thumbnail_id":["2743"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_aioseo_title":[null],"_aioseo_description":[null],"_edit_lock":["1781536122:7"],"_last_translation_edit_mode":["native-editor"],"_edit_last":["7"],"fave_agent_visible":["0"],"fave_agent_whatsapp":["+212660773559"],"_aioseo_keywords":["a:0:{}"],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":["a:0:{}"],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"fave_agent_email":["m.rahali@aaferimmobilier.com"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["0"],"_eael_post_view_count":["1475"],"_g_feedback_shortcode_fba85bb4ab59bc529cc00b583e280c50508b2507":["\n\t\t\t\t[contact-field label=\"Nom\" type=\"name\"  required=\"true\" \/]\n\t\t\t\t[contact-field label=\"E-mail\" type=\"email\" required=\"true\" \/]\n\t\t\t\t[contact-field label=\"Site web\" type=\"url\" \/]\n\t\t\t\t[contact-field label=\"Message\" type=\"textarea\" \/]"],"_g_feedback_shortcode_atts_fba85bb4ab59bc529cc00b583e280c50508b2507":["a:17:{s:2:\"to\";s:37:\"aafer.responsablecommercial@gmail.com\";s:7:\"subject\";s:44:\"[Groupe AAFER immobilier] Sales Agent Dahlia\";s:12:\"show_subject\";s:2:\"no\";s:6:\"widget\";i:0;s:14:\"block_template\";N;s:19:\"block_template_part\";N;s:2:\"id\";i:6994;s:18:\"submit_button_text\";s:7:\"Envoyer\";s:14:\"customThankyou\";s:0:\"\";s:21:\"customThankyouHeading\";s:29:\"Votre message a \u00e9t\u00e9 envoy\u00e9\";s:21:\"customThankyouMessage\";s:30:\"Merci pour votre soumission\u00a0!\";s:22:\"customThankyouRedirect\";s:0:\"\";s:10:\"jetpackCRM\";b:1;s:9:\"className\";N;s:9:\"postToUrl\";N;s:14:\"salesforceData\";N;s:12:\"hiddenFields\";N;}"],"_wpml_word_count":["3"],"_yoast_wpseo_primary_agent_category":[""],"_yoast_wpseo_primary_agent_city":[""],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"fave_agent_logo":["2743"],"fave_agent_mobile":["+212660773559"],"fave_agent_facebook":["https:\/\/www.facebook.com\/AAFERimmobilier"],"fave_agent_linkedin":["https:\/\/www.linkedin.com\/company\/aaferimmoblier\/"],"fave_agent_youtube":["https:\/\/www.youtube.com\/c\/AAFERimmobilier"],"fave_agent_instagram":["https:\/\/www.instagram.com\/aaferimmobilier\/"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sales Agent Dahlia - Groupe AAFER immobilier<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sales Agent Dahlia - Groupe AAFER immobilier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe AAFER immobilier\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T15:07:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aaferimmobilier.com\/wp-content\/uploads\/2016\/03\/Dahlia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/\",\"url\":\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/\",\"name\":\"Sales Agent Dahlia - Groupe AAFER immobilier\",\"isPartOf\":{\"@id\":\"https:\/\/aaferimmobilier.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aaferimmobilier.com\/wp-content\/uploads\/2016\/03\/Dahlia.png\",\"datePublished\":\"2022-01-31T10:22:21+00:00\",\"dateModified\":\"2026-06-15T15:07:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#primaryimage\",\"url\":\"https:\/\/aaferimmobilier.com\/wp-content\/uploads\/2016\/03\/Dahlia.png\",\"contentUrl\":\"https:\/\/aaferimmobilier.com\/wp-content\/uploads\/2016\/03\/Dahlia.png\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/aaferimmobilier.com\/en\/homepage\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0639\u0645\u0644\u0627\u0621\",\"item\":\"https:\/\/aaferimmobilier.com\/ar\/agent\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sales Agent Dahlia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aaferimmobilier.com\/#website\",\"url\":\"https:\/\/aaferimmobilier.com\/\",\"name\":\"Groupe AAFER immobilier\",\"description\":\"Site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aaferimmobilier.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sales Agent Dahlia - Groupe AAFER immobilier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/","og_locale":"en_US","og_type":"article","og_title":"Sales Agent Dahlia - Groupe AAFER immobilier","og_url":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/","og_site_name":"Groupe AAFER immobilier","article_modified_time":"2026-06-15T15:07:45+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/aaferimmobilier.com\/wp-content\/uploads\/2016\/03\/Dahlia.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/","url":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/","name":"Sales Agent Dahlia - Groupe AAFER immobilier","isPartOf":{"@id":"https:\/\/aaferimmobilier.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#primaryimage"},"image":{"@id":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#primaryimage"},"thumbnailUrl":"https:\/\/aaferimmobilier.com\/wp-content\/uploads\/2016\/03\/Dahlia.png","datePublished":"2022-01-31T10:22:21+00:00","dateModified":"2026-06-15T15:07:45+00:00","breadcrumb":{"@id":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#primaryimage","url":"https:\/\/aaferimmobilier.com\/wp-content\/uploads\/2016\/03\/Dahlia.png","contentUrl":"https:\/\/aaferimmobilier.com\/wp-content\/uploads\/2016\/03\/Dahlia.png","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/aaferimmobilier.com\/en\/agent\/sales-agent-dahlia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aaferimmobilier.com\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"\u0639\u0645\u0644\u0627\u0621","item":"https:\/\/aaferimmobilier.com\/ar\/agent\/"},{"@type":"ListItem","position":3,"name":"Sales Agent Dahlia"}]},{"@type":"WebSite","@id":"https:\/\/aaferimmobilier.com\/#website","url":"https:\/\/aaferimmobilier.com\/","name":"Groupe AAFER immobilier","description":"Site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aaferimmobilier.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/agents\/6994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/agents"}],"about":[{"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/types\/houzez_agent"}],"version-history":[{"count":2,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/agents\/6994\/revisions"}],"predecessor-version":[{"id":9225,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/agents\/6994\/revisions\/9225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/media\/2743"}],"wp:attachment":[{"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/media?parent=6994"}],"wp:term":[{"taxonomy":"agent_category","embeddable":true,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/agent_category?post=6994"},{"taxonomy":"agent_city","embeddable":true,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/agent_city?post=6994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}