{"id":6865,"date":"2022-02-10T11:19:39","date_gmt":"2022-02-10T10:19:39","guid":{"rendered":"https:\/\/aaferimmobilier.com\/careers\/"},"modified":"2022-05-14T09:37:45","modified_gmt":"2022-05-14T08:37:45","slug":"careers","status":"publish","type":"page","link":"https:\/\/aaferimmobilier.com\/en\/careers\/","title":{"rendered":"Careers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6865\" class=\"elementor elementor-6865 elementor-3588\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a06e4a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7a06e4a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bed9333\" data-id=\"bed9333\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b1fb9d elementor-widget elementor-widget-spacer\" data-id=\"2b1fb9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0048f12 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0048f12\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Careers<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e063a99 elementor-widget elementor-widget-spacer\" data-id=\"e063a99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc3e0ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc3e0ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fcf311\" data-id=\"8fcf311\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b92730 elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"3b92730\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Give your career a new start, become a part of our team! !<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">Aafer Real Estate Group is constantly looking for talent like you! Share your motivations and experiences with us, and we will be happy to contact you for an interview as soon as a possible ! <\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74914f5 elementor-widget elementor-widget-spacer\" data-id=\"74914f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1bc6c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1bc6c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f013d71\" data-id=\"f013d71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5260888 elementor-widget elementor-widget-shortcode\" data-id=\"5260888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7024-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"7024\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/6865#wpcf7-f7024-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"7024\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7024-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> Full Name*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nom-cv\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"nom_single\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Full Name\" value=\"\" type=\"text\" name=\"nom-cv\" \/><\/span><br \/>\n<label> Email Address*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-cv\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" id=\"email_single\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Email Address\" value=\"\" type=\"email\" name=\"email-cv\" \/><\/span><br \/>\n<label> Address*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"address-cv\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Address\" value=\"\" type=\"text\" name=\"address-cv\" \/><\/span><br \/>\n<label>Phone Number*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-cv\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel form-control\" id=\"tel_single\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Phone Number\" value=\"\" type=\"tel\" name=\"tel-cv\" \/><\/span><br \/>\n<label>Job Title*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"poste-cv\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter Your Job Title\" value=\"\" type=\"text\" name=\"poste-cv\" \/><\/span><br \/>\n<label> Message<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"message-cv\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea form-control\" aria-invalid=\"false\" placeholder=\"Enter Your Message\" name=\"message-cv\"><\/textarea><\/span><br \/>\n<label>Upload Your CV<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"file-cv\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file wpcf7-validates-as-required form-control\" accept=\".pdf\" aria-required=\"true\" aria-invalid=\"false\" type=\"file\" name=\"file-cv\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-primary\" type=\"submit\" value=\"Submit\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"236\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Give your career a new start, become a part of our team! ! Aafer Real Estate Group is constantly looking for talent like you! Share your motivations and experiences with us, and we will be happy to contact you for an interview as soon as a possible !<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template\/template-homepage.php","meta":{"footnotes":""},"class_list":["post-6865","page","type-page","status-publish","hentry"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Careers - Groupe AAFER immobilier<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aaferimmobilier.com\/carrieres\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Careers - Groupe AAFER immobilier\" \/>\n<meta property=\"og:description\" content=\"Give your career a new start, become a part of our team! ! Aafer Real Estate Group is constantly looking for talent like you! Share your motivations and experiences with us, and we will be happy to contact you for an interview as soon as a possible !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aaferimmobilier.com\/carrieres\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe AAFER immobilier\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-14T08:37:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aaferimmobilier.com\/carrieres\/\",\"url\":\"https:\/\/aaferimmobilier.com\/carrieres\/\",\"name\":\"Careers - Groupe AAFER immobilier\",\"isPartOf\":{\"@id\":\"https:\/\/aaferimmobilier.com\/#website\"},\"datePublished\":\"2022-02-10T10:19:39+00:00\",\"dateModified\":\"2022-05-14T08:37:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/aaferimmobilier.com\/carrieres\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aaferimmobilier.com\/carrieres\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aaferimmobilier.com\/carrieres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/aaferimmobilier.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Careers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aaferimmobilier.com\/#website\",\"url\":\"https:\/\/aaferimmobilier.com\/\",\"name\":\"Groupe AAFER immobilier\",\"description\":\"Site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aaferimmobilier.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Careers - Groupe AAFER immobilier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aaferimmobilier.com\/carrieres\/","og_locale":"en_US","og_type":"article","og_title":"Careers - Groupe AAFER immobilier","og_description":"Give your career a new start, become a part of our team! ! Aafer Real Estate Group is constantly looking for talent like you! Share your motivations and experiences with us, and we will be happy to contact you for an interview as soon as a possible !","og_url":"https:\/\/aaferimmobilier.com\/carrieres\/","og_site_name":"Groupe AAFER immobilier","article_modified_time":"2022-05-14T08:37:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aaferimmobilier.com\/carrieres\/","url":"https:\/\/aaferimmobilier.com\/carrieres\/","name":"Careers - Groupe AAFER immobilier","isPartOf":{"@id":"https:\/\/aaferimmobilier.com\/#website"},"datePublished":"2022-02-10T10:19:39+00:00","dateModified":"2022-05-14T08:37:45+00:00","breadcrumb":{"@id":"https:\/\/aaferimmobilier.com\/carrieres\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aaferimmobilier.com\/carrieres\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aaferimmobilier.com\/carrieres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aaferimmobilier.com\/en\/"},{"@type":"ListItem","position":2,"name":"Careers"}]},{"@type":"WebSite","@id":"https:\/\/aaferimmobilier.com\/#website","url":"https:\/\/aaferimmobilier.com\/","name":"Groupe AAFER immobilier","description":"Site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aaferimmobilier.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/pages\/6865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/comments?post=6865"}],"version-history":[{"count":1,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/pages\/6865\/revisions"}],"predecessor-version":[{"id":6866,"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/pages\/6865\/revisions\/6866"}],"wp:attachment":[{"href":"https:\/\/aaferimmobilier.com\/en\/wp-json\/wp\/v2\/media?parent=6865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}